{"id":477,"date":"2023-12-12T14:08:13","date_gmt":"2023-12-12T13:08:13","guid":{"rendered":"https:\/\/japap.info\/latech\/?p=477"},"modified":"2024-06-17T15:19:47","modified_gmt":"2024-06-17T13:19:47","slug":"decouverte-fascinante-pres-de-8-000-pieces-de-monnaie-medievales-et-7-epees-de-lage-de-bronze-deterrees-en-allemagne","status":"publish","type":"post","link":"https:\/\/japap.info\/latech\/2023\/decouverte-fascinante-pres-de-8-000-pieces-de-monnaie-medievales-et-7-epees-de-lage-de-bronze-deterrees-en-allemagne\/477\/","title":{"rendered":"D\u00e9couverte fascinante: pr\u00e8s de 8 000 pi\u00e8ces de monnaie m\u00e9di\u00e9vales et 7 \u00e9p\u00e9es de l&rsquo;\u00c2ge de Bronze d\u00e9terr\u00e9es en Allemagne"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un tr\u00e9sor d&rsquo;artefacts vieux de plusieurs si\u00e8cles en Allemagne dont sept \u00e9p\u00e9es, des milliers de pi\u00e8ces d&rsquo;argent, des bijoux et de la poterie, a <a href=\"https:\/\/japap.info\/latech\/2024\/en-cas-sain-pour-perdre-du-poids-avant-lete-la-recette-facile-et-efficace\/797\/\"><i><u><b>\u00e9t\u00e9<\/b><\/u><\/i><\/a> d\u00e9terr\u00e9 par un groupe de b\u00e9n\u00e9voles conservateurs. Les fouilles ont eu lieu l&rsquo;ann\u00e9e derni\u00e8re \u00e0 trois emplacements diff\u00e9rents dans la campagne allemande, selon le <a href=\"https:\/\/www.regierung-mv.de\/Aktuell\/?id=196662&amp;processor=processor.sa.pressemitteilung\" rel=\"nofollow noopener\" target=\"_blank\">communiqu\u00e9 officiel<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier lieu de <a href=\"https:\/\/japap.info\/latech\/2023\/y-a-t-il-une-difference-entre-le-cerveau-dune-femme-et-celui-dun-homme-ce-que-dit-la-science\/561\/\"><i><u><b>d\u00e9couverte<\/b><\/u><\/i><\/a>, situ\u00e9 pr\u00e8s de la ville de Mirow dans le nord de l&rsquo;Allemagne, contenait des fragments de sept \u00e9p\u00e9es datant de l&rsquo;<a href=\"https:\/\/japap.info\/latech\/2024\/decouvrez-comment-le-vapotage-peut-vieillir-votre-peau-de-10-ans\/833\/\"><i><u><b>\u00c2ge<\/b><\/u><\/i><\/a> du bronze, vieux de 3000 ans. Les arch\u00e9ologues croient que ces armes ont \u00e9t\u00e9 d\u00e9pos\u00e9es l\u00e0 en tant qu&rsquo;offrandes sacrificielles et que leur rupture en plusieurs morceaux est due \u00e0 des dragages ult\u00e9rieurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, ils ont r\u00e9ussi \u00e0 reconstituer les pi\u00e8ces pour former des artefacts complets. La deuxi\u00e8me d\u00e9couverte, pr\u00e8s de l&rsquo;\u00eele allemande de R\u00fcgen \u00e0 environ 200 kilom\u00e8tres de Mirow, a r\u00e9v\u00e9l\u00e9 pr\u00e8s de 6000 pi\u00e8ces d&rsquo;argent m\u00e9di\u00e9vales. La plupart des pi\u00e8ces \u00e9taient rang\u00e9es dans un pot en argile, mais beaucoup \u00e9taient dispers\u00e9es dans le sol. Les arch\u00e9ologues ont remarqu\u00e9 que bien que la plupart des pi\u00e8ces \u00e9taient frapp\u00e9es en Allemagne occidentale, environ 10% venaient d&rsquo;Angleterre, du Danemark, de Boh\u00eame (aujourd&rsquo;hui en R\u00e9publique tch\u00e8que) et de Hongrie, sugg\u00e9rant de possibles relations commerciales dans la r\u00e9gion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette collection a \u00e9t\u00e9 qualifi\u00e9e de plus grand tr\u00e9sor de pi\u00e8ces slaves du 11\u00e8me si\u00e8cle. La derni\u00e8re d\u00e9couverte a \u00e9t\u00e9 faite dans la ville de M\u00f6lln, \u00e9galement dans le nord de l&rsquo;Allemagne. Elle contenait une vari\u00e9t\u00e9 d&rsquo;objets datant \u00e9galement du 11\u00e8me si\u00e8cle, dont un pot rempli de 1700 pi\u00e8ces, un collier de perles en or, cristal de roche et cornaline, des bagues et deux r\u00e9cipients-reliquaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier r\u00e9cipient \u00e9tait en forme de \u00ab\u00a0kaptorga\u00a0\u00bb, un pendentif plat g\u00e9n\u00e9ralement port\u00e9 autour du cou, tandis que le second \u00e9tait inspir\u00e9 d&rsquo;un crucifix. Les arch\u00e9ologues pensent que ces r\u00e9cipients t\u00e9moignent de l&rsquo;influence du christianisme dans la r\u00e9gion \u00e0 cette \u00e9poque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de la <a href=\"https:\/\/japap.info\/latech\/2023\/prix-en-baisse-presentation-du-samsung-galaxy-a25-5g-profitez-de-la-5g-a-petit-prix\/493\/\"><i><u><b>pr\u00e9sentation<\/b><\/u><\/i><\/a>, les responsables du Bureau des monuments historiques de l&rsquo;Allemagne ont remerci\u00e9 les b\u00e9n\u00e9voles pour leurs d\u00e9couvertes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez l&rsquo;extraordinaire tr\u00e9sor m\u00e9di\u00e9val et de l&rsquo;\u00e2ge du Bronze d\u00e9terr\u00e9 en Allemagne : pr\u00e8s de 8 000 pi\u00e8ces de monnaie anciennes et 7 \u00e9p\u00e9es en bronze. Ces trouvailles exceptionnelles nous offrent un aper\u00e7u fascinant de notre histoire et mettent en lumi\u00e8re la richesse de notre patrimoine. Ne manquez pas cette incroyable d\u00e9couverte arch\u00e9ologique qui nous transporte dans le pass\u00e9, t\u00e9moignant de notre pass\u00e9 glorieux. Une v\u00e9ritable aubaine pour les passionn\u00e9s d&rsquo;histoire et les amateurs d&rsquo;art antique.<\/p>\n","protected":false},"author":1,"featured_media":479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"powered_cache_disable_cache":false,"powered_cache_disable_lazyload":false,"powered_cache_disable_css_optimization":false,"powered_cache_disable_js_optimization":false,"powered_cache_disable_js_defer":false,"powered_cache_disable_js_delay":false,"footnotes":""},"categories":[130,14],"tags":[134,132,135,131,133],"class_list":["post-477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archeologie","category-latech","tag-allemagne","tag-decouvertes-archeologiques","tag-epees-de-lage-du-bronze","tag-medieval","tag-pieces-de-monnaie"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/posts\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":1,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"predecessor-version":[{"id":480,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/posts\/477\/revisions\/480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/media\/479"}],"wp:attachment":[{"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}