{"id":605,"date":"2024-03-16T16:23:14","date_gmt":"2024-03-16T15:23:14","guid":{"rendered":"https:\/\/japap.info\/latech\/?p=605"},"modified":"2024-07-03T15:43:36","modified_gmt":"2024-07-03T13:43:36","slug":"ps5-pro-2-4-fois-plus-de-performances-du-ray-tracing-ameliore","status":"publish","type":"post","link":"https:\/\/japap.info\/latech\/2024\/ps5-pro-2-4-fois-plus-de-performances-du-ray-tracing-ameliore\/605\/","title":{"rendered":"PS5 Pro : 2-4 fois plus de performances, du ray-tracing am\u00e9lior\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Sony est rest\u00e9 assez silencieux concernant un potentiel rafra\u00eechissement de mi-parcours pour sa PlayStation 5.<\/strong> En effet, aucune annonce n&rsquo;a \u00e9t\u00e9 faite quant \u00e0 la sortie d&rsquo;une \u00e9ventuelle PS5 Pro. Cependant, les rumeurs et fuites abondantes nous assurent que le \u00ab\u00a0Project Trinity\u00a0\u00bb (nom de code pour la PS5 Pro) est en route, et il arrivera prochainement. En d\u00e9cembre dernier, le site RedGamingTech a publi\u00e9 des sp\u00e9cifications brutes pour la PS5 Pro, sugg\u00e9rant que Sony est en train de <strong>consid\u00e9rablement <a href=\"https:\/\/japap.info\/latech\/2023\/guide-pratique-quel-est-le-rythme-cardiaque-ideal-au-repos-ameliorer-votre-sante-avec-ces-conseils-cles\/513\/\"><i><u><b>am\u00e9liorer<\/b><\/u><\/i><\/a><\/strong> sa console. Bien que cette fuite n&rsquo;ait pas \u00e9t\u00e9 confirm\u00e9e par des preuves tangibles, il y avait de nombreux t\u00e9moignages pour la soutenir. Selon les informateurs, la PS5 Pro serait dot\u00e9e d&rsquo;un processeur Zen 2 \u00e0 8 c\u0153urs, d&rsquo;un GPU \u00e0 30 WGP (60 unit\u00e9s de calcul), de 16 Go de RAM \u00e0 18 Gbps et d&rsquo;un bus m\u00e9moire \u00e0 256 bits.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hier soir, le c\u00e9l\u00e8bre leaker Tom de Moore&rsquo;s Law Is Dead a r\u00e9v\u00e9l\u00e9 une documentation interne de Sony confirmant les rumeurs pr\u00e9c\u00e9dentes et apportant quelques informations suppl\u00e9mentaires sur les performances.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ce document semble \u00eatre une <a href=\"https:\/\/japap.info\/latech\/2023\/prix-en-baisse-presentation-du-samsung-galaxy-a25-5g-profitez-de-la-5g-a-petit-prix\/493\/\"><i><u><b>pr\u00e9sentation<\/b><\/u><\/i><\/a> succincte des arguments de <a href=\"https:\/\/japap.info\/latech\/2023\/la-decision-surprenante-de-la-fondatrice-dune-startup-de-yoga-refus-dachats-a-une-vente-reussie\/552\/\"><i><u><b>vente<\/b><\/u><\/i><\/a> de la PS5 Pro qui ont \u00e9t\u00e9 communiqu\u00e9s aux partenaires de Sony.<\/strong> D&rsquo;apr\u00e8s cette documentation, l&rsquo;APU (unit\u00e9 de traitement acc\u00e9l\u00e9r\u00e9) de la PS5 Pro serait \u00e9quip\u00e9e d&rsquo;un GPU plus puissant, offrant un gain de performances de 45% par rapport \u00e0 la PS5 de base. Bien que ce chiffre soit l\u00e9g\u00e8rement en dessous des rumeurs pr\u00e9c\u00e9dentes qui \u00e9voquaient une am\u00e9lioration de 50 \u00e0 60%, Sony affirme que le GPU de la PS5 Pro est deux \u00e0 quatre fois plus rapide lorsqu&rsquo;il g\u00e8re le ray tracing. Cette affirmation va dans le sens d&rsquo;une fuite ant\u00e9rieure annon\u00e7ant que la console serait deux fois plus rapide pour cette fonctionnalit\u00e9. La version mise \u00e0 niveau de la PS5 est \u00e9galement dot\u00e9e de 300 TOPS (op\u00e9rations en virgule fixe) pour l&rsquo;apprentissage machine sur les 8 bits et de 67 TFLOPS (op\u00e9rations en virgule flottante) pour les 16 bits. La PS5 actuelle a une puissance de 10,28 TFLOPS pour les 32 bits. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En comparaison, la PS5 Pro devrait donc avoir des performances en virgule flottante plus de trois fois sup\u00e9rieures (33,5 TFLOPS apr\u00e8s ajustement pour la diff\u00e9rence de bits) \u00e0 celles de la PS5 de base et presque trois fois sup\u00e9rieures \u00e0 celles de la Xbox Series X (12 TFLOPS). <strong>Bien s\u00fbr, ces performances en virgule flottante ne sont pas n\u00e9cessairement converties d&rsquo;une architecture \u00e0 l&rsquo;autre, mais en prenant en compte toutes ces donn\u00e9es, la version Pro devrait b\u00e9n\u00e9ficier d&rsquo;une am\u00e9lioration de 200% par rapport \u00e0 la version standard de la console.<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de ces donn\u00e9es impressionnantes, Sony a \u00e9galement pr\u00e9sent\u00e9 une <a href=\"https:\/\/japap.info\/latech\/2023\/chevrolet-tahoe-et-suburban-2025-nouveau-design-et-technologie-innovante\/527\/\"><i><u><b>technologie<\/b><\/u><\/i><\/a> de super-r\u00e9solution d\u00e9velopp\u00e9e en interne. La PlayStation Spectral Super Resolution (PSSR) est la r\u00e9ponse de Sony au DLSS (Deep Learning Super Sampling). Selon le document, il s&rsquo;agit d&rsquo;un \u00ab\u00a0anti-cr\u00e9nelage temporel\u00a0\u00bb bas\u00e9 sur l&rsquo;apprentissage automatique. Cette technologie est similaire au DLSS et au FSR (FidelityFX Super Resolution) et prend en charge le HDR complet et la r\u00e9solution dynamique. Cette technologie a \u00e9t\u00e9 con\u00e7ue pour adapter les jeux de la PS5 \u00e0 la r\u00e9solution 4K, mais le document mentionne \u00e9galement la prise en charge de la r\u00e9solution 8K. <strong>\u00c9tant donn\u00e9 que tr\u00e8s peu de jeux PlayStation exploitent actuellement cette r\u00e9solution, Moore&rsquo;s Law Is Dead suppose que le PSSR n&rsquo;est pas simplement un gadget marketing pour la PS5 Pro. Il s&rsquo;agit plut\u00f4t d&rsquo;une technologie que Sony pr\u00e9voit de faire \u00e9voluer et d&rsquo;am\u00e9liorer pour les futures consoles.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sony est rest\u00e9 assez silencieux concernant un potentiel rafra\u00eechissement de mi-parcours pour sa PlayStation 5. En effet, aucune annonce n&rsquo;a \u00e9t\u00e9 faite quant \u00e0 la sortie d&rsquo;une \u00e9ventuelle PS5 Pro. Cependant, les rumeurs et fuites abondantes nous assurent que le \u00ab\u00a0Project Trinity\u00a0\u00bb (nom de code pour la PS5 Pro) est en route, et il arrivera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"powered_cache_disable_cache":false,"powered_cache_disable_lazyload":false,"powered_cache_disable_css_optimization":false,"powered_cache_disable_js_optimization":false,"powered_cache_disable_js_defer":false,"powered_cache_disable_js_delay":false,"footnotes":""},"categories":[14,303,242],"tags":[301,299,189,300,302],"class_list":["post-605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latech","category-jeux","category-technologie","tag-amelioration-du-ray-tracing","tag-documents-sony-divulgues","tag-fuites","tag-performance-accrue","tag-ps5-pro"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/posts\/605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/comments?post=605"}],"version-history":[{"count":1,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/posts\/605\/revisions"}],"predecessor-version":[{"id":607,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/posts\/605\/revisions\/607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/media\/606"}],"wp:attachment":[{"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/media?parent=605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/categories?post=605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/japap.info\/latech\/wp-json\/wp\/v2\/tags?post=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}